{"id":32140,"date":"2023-10-13T15:57:31","date_gmt":"2023-10-13T13:57:31","guid":{"rendered":"https:\/\/www.colaver.it\/?post_type=product&#038;p=32140"},"modified":"2023-10-13T15:57:31","modified_gmt":"2023-10-13T13:57:31","slug":"microscopi-biologici-serie-exolab","status":"publish","type":"product","link":"https:\/\/www.colaver.it\/microscopi-biologici-serie-exolab\/","title":{"rendered":"Microscopi biologici serie EXOLAB"},"content":{"rendered":"<p>I microscopi della serie EXOLAB sono modelli avanzati per osservazioni di routine adatti a laboratori di ricerca, universit\u00e0 e microscopisti esperti.<br \/>\nIl sistema ottico UIS, a correzione infinita di colori, presenta un eccellente micro-immagine ad ogni osservazione.<br \/>\nIl nuovo design permette un utilizzo continuativo del microscopio senza causare affaticamento all\u2019utilizzatore.<br \/>\nMeccanica ergonomica affidabile e precisa.<br \/>\nIl modello EX310TL presenta un sistema d\u2019illuminazione intelligente con memoria dell\u2019obbiettivo utilizzato.<br \/>\nLa maggior parte dei campioni pu\u00f2 essere osservata in luce bianca naturale, altri necessitano di luce pi\u00f9 calda per verificare meglio i dettagli e i colori senza l\u2019utilizzo di filtri. Il modello EX310TL inoltre permette la regolazione della temperatura del colore tra freddo (3000K) e caldo (5600K).<\/p>\n<p>Obiettivi supplementari e accessori a richiesta:<\/p>\n<ul>\n<li>Obiettivo Planacromatico UIS 2x\/0.06<\/li>\n<li>Obiettivo Planacromatico UIS 4x\/0.10<\/li>\n<li>Obiettivo Planacromatico UIS 10x\/0.25<\/li>\n<li>Obiettivo Planacromatico UIS 20x\/0.40<\/li>\n<li>Obiettivo Planacromatico UIS 10x\/0.25 spring<\/li>\n<li>Obiettivo Planacromatico UIS 40x\/0.65 spring<\/li>\n<li>Obiettivo Planacromatico UIS 100x\/1.25 spring<\/li>\n<li>Kit luce polarizzata (filtro polarizzatore-analizzatore)<\/li>\n<li>Slide per campo oscuro (per obbiettivi 4x, 10x, 20x, 40x)<\/li>\n<li>Adattatore CCD 0.5X<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Microscopi della serie EXOLAB per osservazioni di routine in laboratori di ricerca, universit\u00e0 e per microscopisti esperti.<br \/>\nIl sistema ottico UIS, a correzione infinita di colori, presenta un eccellente micro-immagine ad ogni osservazione.<\/p>\n","protected":false},"featured_media":32138,"template":"","meta":[],"product_brand":[],"product_cat":[901],"product_tag":[],"class_list":["post-32140","product","type-product","status-publish","has-post-thumbnail","product_cat-microscopio-da-laboratorio","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/product\/32140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/media\/32138"}],"wp:attachment":[{"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/media?parent=32140"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/product_brand?post=32140"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/product_cat?post=32140"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/product_tag?post=32140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}