{"id":19313,"date":"2019-03-29T10:59:51","date_gmt":"2019-03-29T09:59:51","guid":{"rendered":"http:\/\/cromosoma.eu\/prodotto\/spettrofotometro-uv-vis-onda-touch-uv-21\/"},"modified":"2026-01-30T15:33:26","modified_gmt":"2026-01-30T14:33:26","slug":"spettrofotometro-uv-vis-onda-touch-uv-21","status":"publish","type":"product","link":"https:\/\/www.colaver.it\/spettrofotometro-uv-vis-onda-touch-uv-21\/","title":{"rendered":"Spettrofotometro UV\/VIS ONDA TOUCH UV-21"},"content":{"rendered":"<p>Spettrofotometro UV\/VISIBILE<br \/>range 195 &#8211; 1050 nm<br \/>display a colori 5\u201d TOUCH SCREEN<br \/>banda passante 4 nm, singolo raggio<br \/>sorgenti Tungsteno\/Deuterio,<br \/>memoria flash USB, sistema operativo multilingua.<\/p>\n<p>Funzioni:<br \/>fotometria,<br \/>quantitativa,<br \/>gestione dei file,<br \/>verifica delle prestazioni.<br \/>Fornito con: 4 cuvette in vetro ottico, 2 cuvette in quarzo, supporto celle da 4 posizioni (10 mm), cavo di alimentazione, copertina anti polvere, memoria flash USB e rapporto di taratura.<br \/>Dimensioni esterne (LxPxA) 456x360x185mm. Peso 10.7 kg. Alimentazione 100 \u2013 240 V AC, 50\/60 Hz. Potenza 120 W.<br \/>Cuvette, supporti e accessori a richiesta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Spettrofotometro UV\/VIS 195-1050 nm<br \/>Banda passante 4 nm<br \/>UV-21 &egrave; lo spettrofotometro UV-Vis ideale per analisi di routine e determinazioni quantitative. Le funzionalit&agrave; Fotometria di<br \/>base e Quantitativa ne fanno lo strumento perfetto per un&#8217;analisi rapida e accurata in molti campi di applicazione.<br \/>Cuvette, supporti e accessori a richiesta.<\/p>\n","protected":false},"featured_media":19312,"template":"","meta":[],"product_brand":[],"product_cat":[922],"product_tag":[],"class_list":["post-19313","product","type-product","status-publish","has-post-thumbnail","product_cat-spettrofotometro","pa_millilitri-158","pa_product_call_for_price-no","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/product\/19313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/media\/19312"}],"wp:attachment":[{"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/media?parent=19313"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/product_brand?post=19313"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/product_cat?post=19313"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.colaver.it\/en\/wp-json\/wp\/v2\/product_tag?post=19313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}